{"id":15970,"date":"2007-10-16T15:46:35","date_gmt":"2007-10-16T18:46:35","guid":{"rendered":"https:\/\/screamyell.com.br\/blog\/?p=15970"},"modified":"2018-01-20T15:49:24","modified_gmt":"2018-01-20T18:49:24","slug":"pixies-em-buenos-aires","status":"publish","type":"post","link":"http:\/\/www.screamyell.com.br\/blog\/2007\/10\/16\/pixies-em-buenos-aires\/","title":{"rendered":"Pixies em Buenos Aires?"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-15971 aligncenter\" src=\"http:\/\/www.screamyell.com.br\/blog\/wp-content\/uploads\/2018\/01\/personal.jpg\" alt=\"\" width=\"450\" height=\"244\" srcset=\"http:\/\/www.screamyell.com.br\/blog\/wp-content\/uploads\/2018\/01\/personal.jpg 450w, http:\/\/www.screamyell.com.br\/blog\/wp-content\/uploads\/2018\/01\/personal-300x163.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<p>Calma, calma, calma, n\u00e3o est\u00e1 confirmado ainda. Ali\u00e1s, nem o Wilco est\u00e1 confirmado. Segundo informa\u00e7\u00f5es que recebi, a organiza\u00e7\u00e3o do Personal Fest est\u00e1 conversando seriamente com as duas bandas, mas ainda n\u00e3o bateu o martelo. S\u00f3 parece que o Smashinh Pumpkins melou de vez. Enquanto isso eles j\u00e1 confirmaram nomes \u201cmenores\u201d como Phoenix, Dandy Warhols, Chris Cornell, Happy Mondays e Cypress Hill. Vamos combinar que nenhum deles \u00e9 headliner de festival, vai\u2026<\/p>\n<p>Ps. J\u00e1 avisei na reda\u00e7\u00e3o do iG que se confirmarem Wilco e Pixies eu nunca, NUNCA mais vou ficar reclamando de perder esse ou aquele show. Depois de perder shows das duas bandas no Brasil, se eles tocarem juntos no mesmo festival na Argentina, eu pago minha d\u00edvida comigo mesmo e espero pacientemente at\u00e9 os meus 100 anos por um show do Radiohead. Sem reclamar. Tweedy e Black, me ajudem.<\/p>\n<p>*****************<\/p>\n<p>Desses todos, s\u00f3 o Dandy Warhols est\u00e1 confirmado (naquelas) para o Motomix em S\u00e3o Paulo. O Motomix deve acontecer quase que na mesma semana de dezembro que o Nokia Trends, que j\u00e1 confirmou She Wants Revenge\u2026<\/p>\n<p>*****************<\/p>\n<p>Ser\u00e1 que \u201cIn Rainbows\u201d vendeu mesmo 1 milh\u00e3o e 200 mil c\u00f3pias? Se vendeu, a banda est\u00e1 de parab\u00e9ns pela iniciativa. Ponto a favor \u00e9 que o disco \u00e9\u2026 sensacional. Quem veio direto pra c\u00e1 sem passar pela Revoluttion ou pela capa do Scream &amp; Yell n\u00e3o conferiu meu veredicto final sobre o \u00e1lbum: \u201cIn Rainbows\u201d <a href=\"https:\/\/screamyell.com.br\/site\/2007\/10\/15\/disco-da-semana-in-rainbows-do-radiohead\/\" target=\"_blank\" rel=\"noopener\">n\u00e3o \u00e9 s\u00f3 o disco da semana, \u00e9 o disco do ano<\/a>.<\/p>\n<p>Mas, falando em Radiohead, sabe o que realmente me deixou impressionado: uma leitora da Revoluttion comentou sobre o sucesso de \u201cIn Rainbows\u201d na Last.Fm e fui l\u00e1 conferir. No Top Ten semanal da Last.Fm, os dez lugares est\u00e3o ocupados pelo Radiohead. Os dez! \u201c15 Step\u201d foi ouvida por mais de 67 mil usu\u00e1rios, que juntos somaram 263169 plays da m\u00fasica. \u201cVideotape\u201d, faixa 10 de \u201cIn Rainbows\u201d, aparece em d\u00e9cimo tendo passado pelo player de 56 mil usu\u00e1rios que somaram 211.332 plays.<\/p>\n<p>Mas ainda n\u00e3o \u00e9 isso que me impressionou: o Radiohead lidera a semana com 118.836 ouvintes diferentes que escutaram 3.308.175 de vezes can\u00e7\u00f5es do Radiohead (e ai incluimos todos os discos do Radiohead que foram ouvidos na Last.Fm semana passada). Sabe quem aparece em segundo lugar? Beatles! Quando demonstrei minha surpresa para o meu amigo, ele retrucou: \u201cMas os Beatles lideram toda semana!\u201d. E eu achando que ningu\u00e9m ouvia Beatles hoje em dia\u2026<\/p>\n<p>Olha o Top Ten da Last.Fm (07\/10 a 14\/10)<\/p>\n<p><strong>1 &#8211; Radiohead<br \/>\n<\/strong>118,836 listeners<br \/>\n3,308,175 plays<\/p>\n<p><strong>2 &#8211; The Beatles<\/strong><br \/>\n73,373 listeners<br \/>\n844,600 plays<\/p>\n<p><strong>3 &#8211; Red Hot Chili Peppers<\/strong><br \/>\n64,502 listeners<br \/>\n498,031 plays<\/p>\n<p><strong>4 &#8211; Muse<\/strong><br \/>\n55,563 listeners<br \/>\n570,069 plays<\/p>\n<p><strong>5 &#8211; Coldplay<\/strong><br \/>\n54,165 listeners<br \/>\n364,902 plays<\/p>\n<p><strong>6 &#8211; Foo Fighters<\/strong><br \/>\n53,214 listeners<br \/>\n484,542 plays<\/p>\n<p><strong>7 &#8211; Linkin Park<\/strong><br \/>\n51,245 listeners<br \/>\n474,899 plays<br \/>\n<strong><br \/>\n8 &#8211; Metallica<\/strong><br \/>\n49,381 listeners<br \/>\n413,219 plays<\/p>\n<p><strong>9 &#8211; Nirvana<\/strong><br \/>\n46,759 listeners<br \/>\n307,810 plays<\/p>\n<p><strong>10 &#8211; Pink Floyd<\/strong><br \/>\n45,192 listeners<br \/>\n435,711 plays<\/p>\n<p>*****************<\/p>\n<p>J\u00e1 que falei no Pink Floyd, postei ontem no Mistureba uma notinha falando sobre a edi\u00e7\u00e3o tripla que comemora 40 anos do lan\u00e7amento do \u00e1lbum de estr\u00e9ia da banda, o sensacional \u201cPiper At the Gates of Dawn\u201d.<\/p>\n<p>Pra fechar, um e-mail bacana do F\u00e1bio avisa:<\/p>\n<p>\u201cEu e dois amigos, Carlos Hahn (m\u00fasico e jornalista)\u00a0 e Pedro Hahn (m\u00fasico e cineasta), colocamos no ar o\u00a0<a href=\"http:\/\/www.zoomrs.com\/\"><strong>www.zoomrs.com<\/strong><\/a>, um site sobre m\u00fasica ga\u00facha, n\u00e3o apenas rock, mas m\u00fasica boa em geral, com ecletismo e sem preconceitos. O site\u00a0 tem not\u00edcias que s\u00e3o atualizadas diariamente, e um conte\u00fado com entrevistas, resenhas, etc\u2026 que\u00a0 \u00e9 atualizado mensalmente.\u00a0\u00a0O primeiro tem mat\u00e9rias com os Folk Brothers, Darma L\u00f3vers, etc\u2026\u00a0 E o segundo (prestes a entrar no ar) traz uma mat\u00e9ria com o Thomaz Dreher, gravada no lend\u00e1rio est\u00fadios Dreher. Imperd\u00edvel\u201d1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Calma, calma, calma, n\u00e3o est\u00e1 confirmado ainda. Ali\u00e1s, nem o Wilco est\u00e1 confirmado. Segundo informa\u00e7\u00f5es que recebi, a organiza\u00e7\u00e3o do Personal Fest est\u00e1 conversando seriamente com as duas bandas, mas ainda n\u00e3o bateu o martelo. S\u00f3 parece que o Smashinh Pumpkins melou de vez. Enquanto isso eles j\u00e1 confirmaram nomes \u201cmenores\u201d como Phoenix, Dandy Warhols, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"http:\/\/www.screamyell.com.br\/blog\/wp-json\/wp\/v2\/posts\/15970"}],"collection":[{"href":"http:\/\/www.screamyell.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.screamyell.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.screamyell.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.screamyell.com.br\/blog\/wp-json\/wp\/v2\/comments?post=15970"}],"version-history":[{"count":1,"href":"http:\/\/www.screamyell.com.br\/blog\/wp-json\/wp\/v2\/posts\/15970\/revisions"}],"predecessor-version":[{"id":15972,"href":"http:\/\/www.screamyell.com.br\/blog\/wp-json\/wp\/v2\/posts\/15970\/revisions\/15972"}],"wp:attachment":[{"href":"http:\/\/www.screamyell.com.br\/blog\/wp-json\/wp\/v2\/media?parent=15970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.screamyell.com.br\/blog\/wp-json\/wp\/v2\/categories?post=15970"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.screamyell.com.br\/blog\/wp-json\/wp\/v2\/tags?post=15970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}